{"id":18412,"date":"2024-10-13T08:32:15","date_gmt":"2024-10-13T11:32:15","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18412"},"modified":"2024-10-13T08:32:16","modified_gmt":"2024-10-13T11:32:16","slug":"rcd3838-raios-ou-chamas","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/rcd3838-raios-ou-chamas\/","title":{"rendered":"RCD3838 Raios ou Chamas"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>Seres Brancos Celestiais <br>Atrav\u00e9s de Natalie Glasson<\/strong><\/p>\n\n\n\n<p>O AGORA<\/p>\n\n\n\n<p>10 de outubro de 2024<\/p>\n\n\n\n<p>Sauda\u00e7\u00f5es, amados far\u00f3is de luz, n\u00f3s Somos os Seres Brancos Celestiais. N\u00f3s trazemos a voc\u00eas a bem-aventuran\u00e7a. N\u00f3s os banhamos em bem-aventuran\u00e7a e ativamos a bem-aventuran\u00e7a da pr\u00f3pria ess\u00eancia do seu ser \u2013 como um fogo acendendo, ficando mais forte, preenchendo ou incorporando todo o seu ser.<\/p>\n\n\n\n<p>Imagine esse fogo de bem-aventuran\u00e7a. Talvez seja de uma cor branca com toques de azul, rosa e dourado, ou talvez seja de uma cor completamente diferente. Sua bem-aventuran\u00e7a \u00e9 pessoal para voc\u00ea.<\/p>\n\n\n\n<p>Conforme voc\u00ea acende a bem-aventuran\u00e7a dentro do seu ser, voc\u00ea permite que ela seja incorporada em cada c\u00e9lula e aspecto do seu ser. Isso alimentar\u00e1 tudo o que voc\u00ea \u00e9, tudo o que voc\u00ea faz e tudo o que voc\u00ea cria. Deixe-se ser um fogo de bem-aventuran\u00e7a e deixe esse fogo se espalhar por toda parte.<\/p>\n\n\n\n<p>Hoje n\u00f3s, os Seres Brancos Celestiais, desejamos falar com voc\u00eas sobre o agora \u2013 o momento presente.<\/p>\n\n\n\n<p>N\u00f3s encorajamos voc\u00ea a contemplar o momento presente. Cada momento presente \u00e9 diferente. Cada vez que voc\u00ea pensa no seu momento presente, voc\u00ea pode estar em um espa\u00e7o diferente f\u00edsica e mentalmente ou emocionalmente.<\/p>\n\n\n\n<p>Cada momento presente tem suas pr\u00f3prias b\u00ean\u00e7\u00e3os, tem seus pr\u00f3prios ensinamentos, ilumina\u00e7\u00e3o e realiza\u00e7\u00f5es. Cada momento presente \u00e9 \u00fanico e diferente e, ainda assim, quando voc\u00ea se permite entrar no espa\u00e7o da sua pr\u00f3pria presen\u00e7a, voc\u00ea se permite existir no momento presente \u2013 no agora \u2013 enquanto voc\u00ea se move e navega por toda a sua exist\u00eancia.<\/p>\n\n\n\n<p>Pode parecer imposs\u00edvel estar conectado \u00e0 sua pr\u00f3pria presen\u00e7a enquanto se move por diferentes momentos presentes. Um momento presente \u00e9 quando voc\u00ea est\u00e1 conectado \u00e0 sua presen\u00e7a e ciente de si mesmo e de tudo o que est\u00e1 ao seu redor.<\/p>\n\n\n\n<p>\u00c9 como um alerta alto dentro do seu ser e ao seu redor. \u00c9 um momento de observa\u00e7\u00e3o \u2013 observar sem julgamento \u2013 mesmo sem a necessidade de a\u00e7\u00e3o, simplesmente testemunhar.<\/p>\n\n\n\n<p>Conforme voc\u00ea se permite testemunhar seu pr\u00f3prio ser ou as b\u00ean\u00e7\u00e3os positivas que voc\u00ea \u00e9, assim como as energias presas, voc\u00ea se conecta ao fluxo divino do seu ser e permite que tudo flua com facilidade \u2013 sua alma, sua presen\u00e7a do Criador, suas habilidades espirituais sagradas \u2013 tudo flui com maior facilidade. \u00c9 como se todas as portas estivessem abertas.<\/p>\n\n\n\n<p>As energias presas tamb\u00e9m fluem; elas come\u00e7am a se mover, se desdobrar e ser levadas embora, n\u00e3o sendo mais necess\u00e1rias. Voc\u00ea se v\u00ea sentindo-se mais aberto, mais conectado ao seu eu divino, ao Criador e mais conectado ao seu conhecimento e verdade interior.<\/p>\n\n\n\n<p>Voc\u00ea se permite entrar cada vez mais fundo em sua verdade, interagindo assim consigo mesmo e com seu entorno, suas proje\u00e7\u00f5es e cria\u00e7\u00f5es, com maior conhecimento e foco.<\/p>\n\n\n\n<p>Um prop\u00f3sito surge. Tudo o que voc\u00ea conquistou, tudo o que voc\u00ea observou tem um prop\u00f3sito. Seu pr\u00f3prio ser tem um prop\u00f3sito, no agora. Conforme voc\u00ea come\u00e7a a reconhec\u00ea-lo \u2013 n\u00e3o \u00e9 que voc\u00ea descubra um caminho ou algo que voc\u00ea \u00e9 obrigado a conquistar \u2013 \u00e9 mais que voc\u00ea descubra a si mesmo, sua presen\u00e7a e sua verdade.<\/p>\n\n\n\n<p>Voc\u00ea se permite estar no agora; estar no centro do seu ser sagrado, no centro da sua realidade f\u00edsica e alinhado com o centro do Criador.<\/p>\n\n\n\n<p>Ocorre um alinhamento que permite que voc\u00ea permane\u00e7a em um espa\u00e7o de conex\u00e3o, de doa\u00e7\u00e3o ao seu agora. Voc\u00ea est\u00e1 doando sua ess\u00eancia central, sua verdade, a ess\u00eancia do Criador, ao seu agora; ao seu momento presente, \u00e0 presen\u00e7a do seu ser, ao seu ser proposital.<\/p>\n\n\n\n<p>Voc\u00ea est\u00e1 dando tudo o que voc\u00ea \u00e9 \u2013 toda a realiza\u00e7\u00e3o, todas as vibra\u00e7\u00f5es sagradas, a bem-aventuran\u00e7a, o amor, a paz, tudo o que voc\u00ea \u00e9 \u2013 voc\u00ea est\u00e1 dando isso ao seu agora. Voc\u00ea est\u00e1 dando isso \u00e0 sua presen\u00e7a, a este momento em sua realidade, a cada momento em sua realidade.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 que haja necessidade de manter sua aten\u00e7\u00e3o em sua presen\u00e7a o tempo todo, porque seria imposs\u00edvel viver sua realidade. No entanto, com a conex\u00e3o, algo floresce e se abre dentro de seu ser, e voc\u00ea est\u00e1 seguro em sua presen\u00e7a.<\/p>\n\n\n\n<p>Voc\u00ea est\u00e1 seguro em sua verdade; em tudo o que voc\u00ea \u00e9. Voc\u00ea est\u00e1 dando sua divindade a este momento. Mesmo que sua mente possa estar distra\u00edda em outro lugar, voc\u00ea est\u00e1 constantemente em um espa\u00e7o de dar uma divindade \u00e0 sua presen\u00e7a e ao seu momento presente; ao seu agora.<\/p>\n\n\n\n<p>Mesmo adotando esse entendimento por alguns momentos, pela manh\u00e3, voc\u00ea criar\u00e1 tremendas transforma\u00e7\u00f5es e mudan\u00e7as no seu dia.<\/p>\n\n\n\n<p>Com a pr\u00e1tica, voc\u00ea se ver\u00e1 mergulhando cada vez mais fundo no agora dentro do seu ser; em tudo o que \u00e9 o Criador.<\/p>\n\n\n\n<p>\u00c9 t\u00e3o essencial dar ao seu agora. Essencialmente \u00e9 tudo o que voc\u00ea tem em qualquer momento dado e a mais deliciosa compreens\u00e3o e experi\u00eancia.<\/p>\n\n\n\n<p>Convidamos voc\u00ea a contemplar nossas palavras, a explorar.<\/p>\n\n\n\n<p>~ N\u00f3s Somos os Seres Brancos Celestiais e agradecemos a voc\u00eas<\/p>\n\n\n\n<p>Formata\u00e7\u00e3o e tradu\u00e7\u00e3o \u2013 DE CORA\u00c7\u00c3O A CORA\u00c7\u00c3O<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttp:\/\/www.decoracaoacoracao.blog.br\/\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttp:\/\/stelalecocq.blogspot.com\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/lecocq.wordpress.com\n<\/div><\/figure>\n\n\n\n<p>Instagram \u2013 @blogdecoracaoacoracao<\/p>\n\n\n\n<p>Informa\u00e7\u00f5es e Agendamentos para Mesa Qu\u00e2ntica Estelar, Mesa Pet, Mesa Qu\u00e2ntica 2.0, Sistema Regenerador Ashtariano, Sistema Arcturiano de Cura Multidimensional \u2013 lecocqmuller@gmail.com<\/p>\n\n\n\n<p>E-book \u201cMensagens dos Mestres \u2013 De Cora\u00e7\u00e3o a Cora\u00e7\u00e3o\u201d \u2013 https:\/\/mensagensdosmestres.blogspot.com\/<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-omna-sanctuary wp-block-embed-omna-sanctuary\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"2NluGsXyqe\"><a href=\"https:\/\/omna.org\/\">Home Page<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Home Page&#8221; &#8212; OmNa Sanctuary\" src=\"https:\/\/omna.org\/embed\/#?secret=eB9sUlxNWs#?secret=2NluGsXyqe\" data-secret=\"2NluGsXyqe\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Respeite todos os cr\u00e9ditos ao compartilhar<\/p>\n\n\n\n<p>LUZ!<\/p>\n\n\n\n<p>STELA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seres Brancos Celestiais Atrav\u00e9s de Natalie Glasson O AGORA 10 de outubro de 2024 Sauda\u00e7\u00f5es, amados far\u00f3is de luz, n\u00f3s Somos os Seres Brancos Celestiais. N\u00f3s trazemos a voc\u00eas a bem-aventuran\u00e7a. N\u00f3s os banhamos em bem-aventuran\u00e7a e ativamos a bem-aventuran\u00e7a da pr\u00f3pria ess\u00eancia do seu ser \u2013 como um fogo acendendo, ficando mais forte, preenchendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18412"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18412"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18412\/revisions"}],"predecessor-version":[{"id":18413,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18412\/revisions\/18413"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}