{"id":18410,"date":"2024-10-13T08:30:20","date_gmt":"2024-10-13T11:30:20","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18410"},"modified":"2024-10-13T08:30:22","modified_gmt":"2024-10-13T11:30:22","slug":"plv3891-livro-26-diario-07-05-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3891-livro-26-diario-07-05-2022\/","title":{"rendered":"PLV3891 \u2013 Livro 26 \u2013 Di\u00e1rio, 07\/05\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>07\/05\/2022<\/strong><\/p>\n\n\n\n<p>O mundo espiritual \u00e9 aquilo que eu fizer dele. Ningu\u00e9m pode arvorar-se o direito de, aqui no corpo f\u00edsico, fazer tudo e mais um pouco e, quando passar para o outro lado, encontrar um castelo com tudo o que h\u00e1 de bom. Ao chegar do outro lado da vida, encontrar\u00e1 exatamente aquilo que criou quando encarnado. O ambiente todo que o circundar\u00e1 ser\u00e1 somente aquilo que criou. N\u00e3o haver\u00e1, no seu pedacinho, o inferno, adiante o purgat\u00f3rio e l\u00e1 adiante o c\u00e9u. Do outro lado da vida, o que comanda \u00e9 seu estado de esp\u00edrito. L\u00e1, quando pedir socorro, surgir\u00e3o os socorristas do espa\u00e7o a te atender, auxiliar\u00e3o a que modifiques teu estado de esp\u00edrito, porque ningu\u00e9m ir\u00e1 te fazer um passe de m\u00e1gica e modificar-te. Quem tem que modificar-te \u00e9s tu mesmo. Poder\u00e3o at\u00e9 levar-te a um hospital espiritual, mas quem vai te curar, te equilibrar, \u00e9s tu mesmo. Do outro lado da vida, n\u00e3o vais encontrar a Deus, n\u00e3o vais encontrar a Jesus, mas vais encontrar outros esp\u00edritos como tu mesmo, s\u00f3 que mais evolu\u00eddos, equilibrados e especialmente conscientes do Somos Todos Um e, sabedores que voc\u00ea \u00e9 um irm\u00e3o como todos os outros seres, te dar\u00e3o a m\u00e3o, n\u00e3o para te arrastar, mas para que sintas a for\u00e7a de voc\u00ea mesmo mudar, buscando coragem e at\u00e9 ousadia em conseguir evoluir. Nessas alturas, tua mente j\u00e1 deve estar desimpregnada da energia negativa que levaste para o outro lado da vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>07\/05\/2022 O mundo espiritual \u00e9 aquilo que eu fizer dele. Ningu\u00e9m pode arvorar-se o direito de, aqui no corpo f\u00edsico, fazer tudo e mais um pouco e, quando passar para o outro lado, encontrar um castelo com tudo o que h\u00e1 de bom. Ao chegar do outro lado da vida, encontrar\u00e1 exatamente aquilo que criou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18410"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18410"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18410\/revisions"}],"predecessor-version":[{"id":18411,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18410\/revisions\/18411"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}