{"id":18207,"date":"2024-09-01T08:57:13","date_gmt":"2024-09-01T11:57:13","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18207"},"modified":"2024-09-01T08:57:14","modified_gmt":"2024-09-01T11:57:14","slug":"plv3851-livro-26-diario-27-03-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3851-livro-26-diario-27-03-2022\/","title":{"rendered":"PLV3851 &#8211; Livro 26 &#8211; Di\u00e1rio, 27\/03\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>27\/03\/2022<\/strong><\/p>\n\n\n\n<p>Nos esquecemos, n\u00e3o nos damos conta, ou qui\u00e7\u00e1, nem sabemos a coisa mais importante de nossa exist\u00eancia. O conhecimento, a conscientiza\u00e7\u00e3o dele endireita todos os caminhos. Somos baseados nas prega\u00e7\u00f5es das igrejas: Deus faz um milagre, Deus abre os caminhos, Deus nos cuida, abre a manh\u00e3 com lindo sol e fica zelando ao lado de nossa cama, em s\u00edntese, um Deus mordomo. No livro Conversando com Deus, h\u00e1 uma passagem em que Deus diz: \u201cDeus apenas observa\u201d. Essa \u00e9 nossa realidade. Precisamos nos convencer de que n\u00f3s \u00e9 que fazemos. Recebemos, desde nossa individualiza\u00e7\u00e3o o maior poder do universo, o pensamento. Este \u00e9 que faz nossa vida na mat\u00e9ria ou fora dela. Este \u00e9 que aplica aquilo que Deus disse a Ad\u00e3o e Eva: \u201ccrescei e multiplicai-vos\u201d. At\u00e9 hoje, ainda acreditam que Deus disse para multiplicar a descend\u00eancia. Precisamos nos deitar sobre essa realidade, que somos, pelo pensamento, os criadores de nossa realidade individual ou coletiva. Como se diz, recebemos a faca e o queijo, precisamos agora bem us\u00e1-los, porque o pensamento \u00e9 que nos torna aquilo que somos. O pensamento \u00e9 que abre as portas do conhecimento e encaminha nossa evolu\u00e7\u00e3o, nos ajuda a vencer etapas, a construir os degraus evolutivos de nossa pr\u00f3pria exist\u00eancia. O que nos falta \u00e9 a perspic\u00e1cia para unir a mat\u00e9ria e o esp\u00edrito em uma s\u00f3 individualidade, porque a mat\u00e9ria sou eu, o esp\u00edrito tamb\u00e9m sou eu. Desculpem a m\u00e1 compara\u00e7\u00e3o: de m\u00e1scara, somos o palha\u00e7o e, sem a m\u00e1scara, somos o indiv\u00edduo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>27\/03\/2022 Nos esquecemos, n\u00e3o nos damos conta, ou qui\u00e7\u00e1, nem sabemos a coisa mais importante de nossa exist\u00eancia. O conhecimento, a conscientiza\u00e7\u00e3o dele endireita todos os caminhos. Somos baseados nas prega\u00e7\u00f5es das igrejas: Deus faz um milagre, Deus abre os caminhos, Deus nos cuida, abre a manh\u00e3 com lindo sol e fica zelando ao lado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18207"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18207"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18207\/revisions"}],"predecessor-version":[{"id":18208,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18207\/revisions\/18208"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}