{"id":18177,"date":"2024-08-26T08:32:51","date_gmt":"2024-08-26T11:32:51","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18177"},"modified":"2024-08-26T08:32:53","modified_gmt":"2024-08-26T11:32:53","slug":"plv3845-livro-26-diario-21-03-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3845-livro-26-diario-21-03-2022\/","title":{"rendered":"PLV3845 &#8211; Livro 26 &#8211; Di\u00e1rio, 21\/03\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>21\/03\/2022<\/strong><\/p>\n\n\n\n<p>Estamos no momento exato para encaminhar nosso futuro, que \u00e9 a nossa evolu\u00e7\u00e3o espiritual. Esse momento de energias concentradas e altamente manipuladas para fixar no planeta Terra essa nova era de prosperidade, de evolu\u00e7\u00e3o, de b\u00ean\u00e7\u00e3os para essa humanidade que ainda pouca aten\u00e7\u00e3o d\u00e1 a esse per\u00edodo in\u00e9dito para nosso planeta. Essa humanidade n\u00e3o se deu conta, ainda, da import\u00e2ncia deste per\u00edodo, que para muitos \u00e9 um vale de l\u00e1grimas, mas em que logo vir\u00e1 a bonan\u00e7a e trar\u00e1 junto a luz que haver\u00e1 de iluminar as trevas, para que o caminho se torne mais suave. A toda bonan\u00e7a, sempre precede a tempestade, que serve para limpar o ar de tudo quanto \u00e9 miasma que esteja infectando os ares e as pessoas. Geralmente, esquecemos um fator muito importante: simplificando, diremos apenas \u201cSomos Todos Um\u201d. Por ora, n\u00e3o \u00e9 ainda nossa consci\u00eancia, mas ela come\u00e7ar\u00e1 a impregnar-se em cada ser que consiga ultrapassar a porta da quinta dimens\u00e3o. Aqueles seres de outras casas do Pai que j\u00e1 adentraram a outras dimens\u00f5es maiores, est\u00e3o a nos auxiliar com sua energia e sua presen\u00e7a, embora oculta, a nos ajudar a absorver essa nova energia que ser\u00e1 o press\u00e1gio de evolu\u00e7\u00e3o mais elevada. Pela consci\u00eancia que t\u00eam, \u201cSomos Todos Um\u201d, e toda ajuda que derem aos outros estar\u00e3o dando a si mesmos. Porque \u201c\u00c9 dando que se recebe, \u00e9 perdoando que se \u00e9 perdoado, e \u00e9 morrendo, para as coisas materiais, que se vive para a vida eterna\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>21\/03\/2022 Estamos no momento exato para encaminhar nosso futuro, que \u00e9 a nossa evolu\u00e7\u00e3o espiritual. Esse momento de energias concentradas e altamente manipuladas para fixar no planeta Terra essa nova era de prosperidade, de evolu\u00e7\u00e3o, de b\u00ean\u00e7\u00e3os para essa humanidade que ainda pouca aten\u00e7\u00e3o d\u00e1 a esse per\u00edodo in\u00e9dito para nosso planeta. Essa humanidade n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18177"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18177"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18177\/revisions"}],"predecessor-version":[{"id":18178,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18177\/revisions\/18178"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}