{"id":18134,"date":"2024-08-16T08:20:31","date_gmt":"2024-08-16T11:20:31","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18134"},"modified":"2024-08-16T08:20:33","modified_gmt":"2024-08-16T11:20:33","slug":"plv3836-livro-26-diario-11-03-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3836-livro-26-diario-11-03-2022\/","title":{"rendered":"PLV3836 &#8211; Livro 26 &#8211; Di\u00e1rio, 11\/03\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>11\/03\/2022<\/strong><\/p>\n\n\n\n<p>O plano de Deus para todos os seres \u00e9 que consigam alcan\u00e7ar a perfei\u00e7\u00e3o dentro de seu reino. Ao ser humano, deu a liberdade, atrav\u00e9s de suas pr\u00f3prias cria\u00e7\u00f5es, de alcan\u00e7ar a perfei\u00e7\u00e3o, que \u00e9 a mestria. Essa liberdade vem atrelada \u00e0 responsabilidade pelas suas cria\u00e7\u00f5es. \u00c9 a Lei do Livre-arb\u00edtrio: em s\u00edntese, de tudo o que fizer ser\u00e1 responsabilizado. Aquilo que o evolui elevar\u00e1 sua evolu\u00e7\u00e3o espiritual, e aquilo que fizer e for contra a Grande Lei ter\u00e1 que ressarcir. No seu retorno a um corpo f\u00edsico, ser\u00e1 o momento de quitar seus malfeitos, \u00e9 o carma de suas vidas passadas. O maior problema est\u00e1 em que o ser humano n\u00e3o liga sua vida atual ao resultado de suas vidas passadas. Para a grande maioria, e inclusive para religi\u00f5es, o nascimento aqui na Terra simplesmente caiu do C\u00e9u ou, como dizem para as crian\u00e7as, \u201ca cegonha \u00e9 que trouxe\u201d. Com isso, jamais ir\u00e3o ligar seu presente a seu passado. Essa ignor\u00e2ncia d\u00e1 aos d\u00e9spotas o poder e a liberdade de fazer o que bem lhe vier na telha. S\u00e3o capazes de criar guerras para dizer \u201ceu sou mais forte\u201d. Fazem toda a sorte de sandices, porque n\u00e3o creem que ter\u00e3o que resgatar. Dessa forma, n\u00e3o importa o que fa\u00e7am aos outros, porque tudo vai terminar com a morte. Por mais que o plano Superior projete energias as mais sublimes, escorrer\u00e1 sobre seus corpos como se fosse a chuva. S\u00f3 aprendem com a dor no presente, porque o futuro vai somente at\u00e9 o cemit\u00e9rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/03\/2022 O plano de Deus para todos os seres \u00e9 que consigam alcan\u00e7ar a perfei\u00e7\u00e3o dentro de seu reino. Ao ser humano, deu a liberdade, atrav\u00e9s de suas pr\u00f3prias cria\u00e7\u00f5es, de alcan\u00e7ar a perfei\u00e7\u00e3o, que \u00e9 a mestria. Essa liberdade vem atrelada \u00e0 responsabilidade pelas suas cria\u00e7\u00f5es. \u00c9 a Lei do Livre-arb\u00edtrio: em s\u00edntese, de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18134"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18134"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18134\/revisions"}],"predecessor-version":[{"id":18135,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18134\/revisions\/18135"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}