{"id":18010,"date":"2024-07-19T09:28:28","date_gmt":"2024-07-19T12:28:28","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=18010"},"modified":"2024-07-19T09:28:30","modified_gmt":"2024-07-19T12:28:30","slug":"plv3808-livro-26-diario-11-02-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3808-livro-26-diario-11-02-2022\/","title":{"rendered":"PLV3808 &#8211; Livro 26 &#8211; Di\u00e1rio, 11\/02\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>11\/02\/2022<\/strong><\/p>\n\n\n\n<p>Os dias est\u00e3o se aproximando em que haver\u00e1, \u00e0 vista de toda a humanidade, a necessidade de come\u00e7ar a andar no reto caminho. At\u00e9 agora, andou-se tal qual son\u00e2mbulo ou b\u00eabado mesmo, sem conseguir distinguir o acostamento da estrada. Andava-se tr\u00f4pego, como se as pernas estivessem quebradas. N\u00e3o se tinha rumo, n\u00e3o se tinha o Norte, n\u00e3o se tinha objetivo para essa vida. Logo, logo, precisa-se mudar e ter\u00e1 que ser uma mudan\u00e7a muito profunda, que parta do mais profundo \u00e2mago de nossa alma, de uma mudan\u00e7a que ter\u00e1 que ser at\u00e9 a raiz dos cabelos. Isso n\u00e3o \u00e9 somente para alguns indiv\u00edduos; a inclus\u00e3o ter\u00e1 que ser de todos, porque aqueles que n\u00e3o se inclu\u00edrem nessa metamorfose simplesmente n\u00e3o ver\u00e3o a Nova Jerusal\u00e9m, n\u00e3o poder\u00e3o habilitar esse novo Jardim do \u00c9den, que ser\u00e1 a nova Terra, na quinta dimens\u00e3o. Os que preferem a mat\u00e9ria ao inv\u00e9s do esp\u00edrito ser\u00e3o expulsos, exilados em outros planetas, ao n\u00edvel de homens das cavernas, e l\u00e1 ficar\u00e3o no astral deste novo planeta at\u00e9 convencer-se de que seu \u00fanico objetivo deve ser sua evolu\u00e7\u00e3o espiritual. N\u00e3o deixa de ser um castigo, mas ser\u00e1 uma grande oportunidade para fazer aquilo que se prop\u00f4s a fazer quando aqui na Terra. Quando n\u00e3o vai por bem, de sua vontade, de seu empenho, de sua op\u00e7\u00e3o, precisa de uma baioneta cutucando seu traseiro. O \u00fanico objetivo de nossa cria\u00e7\u00e3o como individualidade \u00e9 sermos Deuses, como Deus o \u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/02\/2022 Os dias est\u00e3o se aproximando em que haver\u00e1, \u00e0 vista de toda a humanidade, a necessidade de come\u00e7ar a andar no reto caminho. At\u00e9 agora, andou-se tal qual son\u00e2mbulo ou b\u00eabado mesmo, sem conseguir distinguir o acostamento da estrada. Andava-se tr\u00f4pego, como se as pernas estivessem quebradas. N\u00e3o se tinha rumo, n\u00e3o se tinha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18010"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=18010"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18010\/revisions"}],"predecessor-version":[{"id":18011,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/18010\/revisions\/18011"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=18010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=18010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=18010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}