{"id":17889,"date":"2024-06-20T08:45:02","date_gmt":"2024-06-20T11:45:02","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=17889"},"modified":"2024-06-20T08:49:30","modified_gmt":"2024-06-20T11:49:30","slug":"plv3779-livro-26-diario-14-01-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3779-livro-26-diario-14-01-2022\/","title":{"rendered":"PLV3779 &#8211; Livro 26 &#8211; Di\u00e1rio, 13\/01\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>13\/01\/2022<\/strong><\/p>\n\n\n\n<p>O princ\u00edpio da vida \u00e9 um s\u00f3. Onde ela surgiu, foi criada pela mesma energia que dirige o universo. Todo o princ\u00edpio de vida tem o poder criador, que \u00e9, conseguir reproduzir-se e, o poder regedor que lhe garante a perfeita continuidade daquela vida, sem perder suas caracter\u00edsticas iniciais. Toda energia \u00e9 secundada pelo Deus Uno, sem a qual o universo seria uma tranqueira. Para reger e dar estabilidade a tudo isso, precisa de uma energia maior que o universo, e essa energia \u00e9 um Deus, a \u00fanica forma de estabelecer harmonia e estabilidade disso que chamamos de universo. Em s\u00edntese, partindo do \u00e1tomo, os corpos, os planetas, os sistemas solares, as gal\u00e1xias e as gal\u00e1xias de gal\u00e1xias e, assim, o universo todo. Isso tudo \u00e9 uma vida s\u00f3, variando apenas a intensidade e a frequ\u00eancia em cada unidade. Infelizmente, a ci\u00eancia dos homens se ateve somente \u00e0 mat\u00e9ria e n\u00e3o se preocupou em saber o que \u00e9 que d\u00e1 exist\u00eancia \u00e0 mat\u00e9ria. Sua ci\u00eancia \u00e9 a perneta, porque a outra perna que d\u00e1 a estabilidade \u00e0 mat\u00e9ria \u00e9 a energia. Essa energia foi apelidada de centenas de nomes diferentes, mas que executam a mesma coisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\/01\/2022 O princ\u00edpio da vida \u00e9 um s\u00f3. Onde ela surgiu, foi criada pela mesma energia que dirige o universo. Todo o princ\u00edpio de vida tem o poder criador, que \u00e9, conseguir reproduzir-se e, o poder regedor que lhe garante a perfeita continuidade daquela vida, sem perder suas caracter\u00edsticas iniciais. Toda energia \u00e9 secundada pelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17889"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=17889"}],"version-history":[{"count":2,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17889\/revisions"}],"predecessor-version":[{"id":17892,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17889\/revisions\/17892"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=17889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=17889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=17889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}