{"id":17864,"date":"2024-06-14T08:34:47","date_gmt":"2024-06-14T11:34:47","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=17864"},"modified":"2024-06-14T08:34:49","modified_gmt":"2024-06-14T11:34:49","slug":"plv3773-livro-26-diario-07-01-2022","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3773-livro-26-diario-07-01-2022\/","title":{"rendered":"PLV3773 &#8211; Livro 26 &#8211; Di\u00e1rio, 07\/01\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>07\/01\/2022<\/strong><\/p>\n\n\n\n<p>A pressa sempre foi inimiga da perfei\u00e7\u00e3o. Nada no universo \u00e9 feito, \u00e9 realizado, \u00e9 estabelecido com pressa. Tudo leva seu tempo para se realizar. Tudo \u00e9 criado, cresce e depois amadurece (est\u00e1 pronto). Para se ter uma ideia, a Terra levou um tempo relativamente longo para ser criada, n\u00e3o se sabe e nem se tem condi\u00e7\u00f5es de precisar. Sua imagem foi projetada na luz primordial pelos Deuses H\u00e9lios e Vesta, que s\u00e3o os Deuses do Sol. Foram convidados os sete Elohins e os sete Devas para fixarem essa imagem imantada na luz primordial. N\u00e3o se sabe tamb\u00e9m quanto tempo foi necess\u00e1rio para transformar a imagem em realidade. Depois da fixa\u00e7\u00e3o completa feita pelos e Elohins e Devas, a Terra come\u00e7ou a girar sobre seu pr\u00f3prio eixo. Assim, n\u00e3o sei se iniciou na Primeira, na Segunda ou j\u00e1 foi estabelecida na terceira dimens\u00e3o. Isso s\u00f3 Deus o sabe. S\u00f3 sei uma coisa: a ci\u00eancia dos homens jamais ir\u00e1 precisar h\u00e1 quanto tempo a Terra foi criada. Para ela, tudo aparece como um sopro, caiu do c\u00e9u. O ser humano, que com toda a capacidade que tem, tira de sua mente e faz surgir na mat\u00e9ria, no universo, n\u00e3o se deu conta ainda de que tem a maior for\u00e7a do universo: seu pensamento. \u00c9 s\u00f3 ver tudo o que h\u00e1, que existe, muitas vezes sem ser percebido e aquilatado por ele, surgiu do pensamento de algu\u00e9m. Tudo tem uma origem, o pensamento, podendo ser do pr\u00f3prio ser humano ou de algum ser superior a ele e por que n\u00e3o de uma Divindade?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>07\/01\/2022 A pressa sempre foi inimiga da perfei\u00e7\u00e3o. Nada no universo \u00e9 feito, \u00e9 realizado, \u00e9 estabelecido com pressa. Tudo leva seu tempo para se realizar. Tudo \u00e9 criado, cresce e depois amadurece (est\u00e1 pronto). Para se ter uma ideia, a Terra levou um tempo relativamente longo para ser criada, n\u00e3o se sabe e nem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17864"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=17864"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17864\/revisions"}],"predecessor-version":[{"id":17865,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/17864\/revisions\/17865"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=17864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=17864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=17864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}