{"id":16398,"date":"2023-07-03T08:38:18","date_gmt":"2023-07-03T11:38:18","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16398"},"modified":"2023-07-03T08:38:20","modified_gmt":"2023-07-03T11:38:20","slug":"plv3436-livro-24-diario-03-02-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3436-livro-24-diario-03-02-2021\/","title":{"rendered":"PLV3436 &#8211; Livro 24 &#8211; Di\u00e1rio, 03\/02\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>03\/02\/2021<\/strong><\/p>\n\n\n\n<p>Nas nossas andan\u00e7as pelo universo, j\u00e1 residimos em muitos planetas, pois foi necess\u00e1rio para o casamento entre a energia nossa com a energia do planeta. As duas energias n\u00e3o precisam ser absolutamente iguais, mas \u00e9 necess\u00e1rio que possam se suportar. Apenas para exemplificar: \u00e1gua e vinho, tudo bem. S\u00f3 n\u00e3o pode ser \u00e1gua e \u00f3leo, a\u00ed, n\u00e3o \u00e9 poss\u00edvel. Isso \u00e9 exatamente o que est\u00e1 acontecendo na Terra. Muitos esp\u00edritos j\u00e1 n\u00e3o vibram em conson\u00e2ncia com as energias da Terra, quando ainda encarnados, e est\u00e3o aguardando o seu desencarne para serem levados para outros planetas compat\u00edveis. Muitos, que estavam nos astrais da Terra, j\u00e1 foram levados para outros planetas, com o qu\u00ea Jav\u00e9 chama de navio, que nada mais s\u00e3o do que suas naves espaciais. Est\u00e1 se aproximando a hora de passarmos pela peneira que, diz Jesus, \u201c<em>separar\u00e1 o joio do trigo<\/em>\u201d. Se nossa energia for suficientemente elevada, seguiremos com a Terra para a quinta dimens\u00e3o, se n\u00e3o, o nosso destino ser\u00e1 os por\u00f5es dos navios. Estamos numa \u00e9poca em que n\u00e3o podemos mais nos desculpar pela ignor\u00e2ncia. Todo o conhecimento j\u00e1 est\u00e1 dispon\u00edvel, para, ao menos, nos direcionar para a evolu\u00e7\u00e3o espiritual e dar ao corpo f\u00edsico sua real dimens\u00e3o, ser um instrumento para a evolu\u00e7\u00e3o do esp\u00edrito. Na balan\u00e7a da vida, at\u00e9 agora s\u00f3 acrescentamos conhecimentos no prato da mat\u00e9ria. Antes que seja tarde, precisamos inverter e p\u00f4r conhecimentos tamb\u00e9m no prato do esp\u00edrito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>03\/02\/2021 Nas nossas andan\u00e7as pelo universo, j\u00e1 residimos em muitos planetas, pois foi necess\u00e1rio para o casamento entre a energia nossa com a energia do planeta. As duas energias n\u00e3o precisam ser absolutamente iguais, mas \u00e9 necess\u00e1rio que possam se suportar. Apenas para exemplificar: \u00e1gua e vinho, tudo bem. S\u00f3 n\u00e3o pode ser \u00e1gua e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16398"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16398"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16398\/revisions"}],"predecessor-version":[{"id":16399,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16398\/revisions\/16399"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}