{"id":16336,"date":"2023-06-19T08:22:08","date_gmt":"2023-06-19T11:22:08","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16336"},"modified":"2023-06-19T08:22:11","modified_gmt":"2023-06-19T11:22:11","slug":"plv3422-livro-24-diario-20-01-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3422-livro-24-diario-20-01-2021\/","title":{"rendered":"PLV3422 &#8211; Livro 24 &#8211; Di\u00e1rio, 20\/01\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>20\/01\/2021<\/strong><\/p>\n\n\n\n<p>O sinal dos tempos est\u00e1 a\u00ed. Ningu\u00e9m mais se entende, cada um puxa para um lado diferente. O comando maior, que solapa os interesses da harmonia de uma popula\u00e7\u00e3o est\u00e1 no dinheiro. Essa cria insana da humanidade est\u00e1 destruindo as bases de sustenta\u00e7\u00e3o de uma popula\u00e7\u00e3o e, por que n\u00e3o dizer, do planeta? Grande parte dos seres humanos se vendem a pre\u00e7o de bananas. N\u00e3o existem mais os princ\u00edpios que regem os atos humanos e que os identificavam como seres pensantes e capacitados de discernir entre o bem e o mal. Agora, e ali\u00e1s de um tempo para c\u00e1, governos n\u00e3o se preocupam pelo bem de sua popula\u00e7\u00e3o, mas como com quanto ir\u00e3o surrupiar fazendo, de uma forma ou outra, deslizar para seus bolsos. H\u00e1 exce\u00e7\u00f5es, mas a grande maioria rouba na calada da noite e no dia seguinte d\u00e1 um trocado, e h\u00e1 seres humanos que at\u00e9 matam para defender esses locupletadores do sangue, suor e l\u00e1grimas de uma popula\u00e7\u00e3o desvalida e que muitas vezes n\u00e3o tem nem \u00e1gua para dessedentar-se. S\u00e3o pobres e infelizes, que foram criados na ignor\u00e2ncia das letras, tratados como escravos e obrigados a carregar a pecha de vagabundos. Esses, ainda pode-se desculpar, mas aqueles que vivem na boa vida, com ganhos sem bases legais, ou tamb\u00e9m, pode ser que seja, mas que extorquem o racioc\u00ednio l\u00f3gico para defender quem rouba uma na\u00e7\u00e3o, forma com esses uma quadrilha, sem sentimentos, sem princ\u00edpios, sem moral e sem vergonha na cara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>20\/01\/2021 O sinal dos tempos est\u00e1 a\u00ed. Ningu\u00e9m mais se entende, cada um puxa para um lado diferente. O comando maior, que solapa os interesses da harmonia de uma popula\u00e7\u00e3o est\u00e1 no dinheiro. Essa cria insana da humanidade est\u00e1 destruindo as bases de sustenta\u00e7\u00e3o de uma popula\u00e7\u00e3o e, por que n\u00e3o dizer, do planeta? Grande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16336"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16336"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16336\/revisions"}],"predecessor-version":[{"id":16337,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16336\/revisions\/16337"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}