{"id":16331,"date":"2023-06-18T08:38:04","date_gmt":"2023-06-18T11:38:04","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16331"},"modified":"2023-06-18T08:38:07","modified_gmt":"2023-06-18T11:38:07","slug":"plv3421-livro-24-diario-19-01-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3421-livro-24-diario-19-01-2021\/","title":{"rendered":"PLV3421 &#8211; Livro 24 &#8211; Di\u00e1rio, 19\/01\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>19\/01\/2021<\/strong><\/p>\n\n\n\n<p>Pode-se dizer que, para o corpo f\u00edsico, a vida passa. Mas, para o esp\u00edrito, a vida continua, ela n\u00e3o tem limites de tempo, mas tem um limite de evolu\u00e7\u00e3o, quando retorna novamente ao Deus Uno Pai\/M\u00e3e. Quando no corpo, o esp\u00edrito n\u00e3o tem muita vez, fatalmente o consciente do corpo ter\u00e1 dificuldade de intelectualizar muita coisa que se refere muito mais ao esp\u00edrito que \u00e0 mat\u00e9ria. A mat\u00e9ria, para poder receber certos conhecimentos que est\u00e3o escondidos, precisa aliar-se ao esp\u00edrito na sua busca. Quando h\u00e1 a uni\u00e3o do corpo com o esp\u00edrito, com o mesmo objetivo, h\u00e1 a evolu\u00e7\u00e3o de ambos. O corpo, quando consciente dessa uni\u00e3o, tudo se torna mais f\u00e1cil e mais r\u00e1pido tanto nas lides normais das atividades do corpo como na compreens\u00e3o, na a\u00e7\u00e3o e na evolu\u00e7\u00e3o do esp\u00edrito. S\u00e3o aqueles homens que, como diz Jesus: \u201c<em>Ordena a essa montanha que se retire daqui para l\u00e1 e ela o far\u00e1<\/em>\u201d. S\u00e3o homens que ordenam ao universo, pelo pensamento, e este obedecer\u00e1 \u00e0s suas ordens. Esse poder est\u00e1 vinculado \u00e0 dualidade corpo\/esp\u00edrito. Por mais evolu\u00eddo seja o esp\u00edrito, se o corpo n\u00e3o participar, o esp\u00edrito nada conseguir\u00e1. Corpo e esp\u00edrito precisam andar juntos, para que haja uma evolu\u00e7\u00e3o mais r\u00e1pida e harm\u00f4nica. A participa\u00e7\u00e3o do corpo \u00e9 enquanto o esp\u00edrito estiver dentro dele, mas, depois da separa\u00e7\u00e3o, os \u00e1tomos que o formavam receber\u00e3o os devidos b\u00f4nus de sua participa\u00e7\u00e3o na dualidade. At\u00e9 d\u00e1 para dizer que h\u00e1 a prova disso, corpos que auxiliaram o esp\u00edrito e n\u00e3o se decompuseram em seus \u00e1tomos, mas continuam como a dizer: \u201cFui um bom instrumento do esp\u00edrito\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/01\/2021 Pode-se dizer que, para o corpo f\u00edsico, a vida passa. Mas, para o esp\u00edrito, a vida continua, ela n\u00e3o tem limites de tempo, mas tem um limite de evolu\u00e7\u00e3o, quando retorna novamente ao Deus Uno Pai\/M\u00e3e. Quando no corpo, o esp\u00edrito n\u00e3o tem muita vez, fatalmente o consciente do corpo ter\u00e1 dificuldade de intelectualizar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16331"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16331"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16331\/revisions"}],"predecessor-version":[{"id":16332,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16331\/revisions\/16332"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}