{"id":16319,"date":"2023-06-15T08:05:31","date_gmt":"2023-06-15T11:05:31","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16319"},"modified":"2023-06-15T08:05:36","modified_gmt":"2023-06-15T11:05:36","slug":"plv3418-livro-24-diario-16-01-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3418-livro-24-diario-16-01-2021\/","title":{"rendered":"PLV3418 &#8211; Livro 24 &#8211; Di\u00e1rio, 16\/01\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>16\/01\/2021<\/strong><\/p>\n\n\n\n<p>Aquilo que nos acontece na vida \u00e9 apenas o espelho de nossos pensamentos, nossas palavras e nossas obras de vidas passadas. Esquecemos que somos uma part\u00edcula Divina envolta em um corpo de carne e disso resulta que somos tamb\u00e9m criadores de tudo o que nos diz a respeito. Temos o livre-arb\u00edtrio e disso tudo o que fizemos seremos responsabilizados. Aquilo que nos serviu de evolu\u00e7\u00e3o nos evoluir\u00e1, e aquilo que infracionou a lei nos ser\u00e1 cobrado como carma. N\u00e3o estamos na vida a passeio, descemos \u00e0 mat\u00e9ria para aqui experienciar os conhecimentos e evoluir. Essa descida n\u00e3o \u00e9 um mero acaso, h\u00e1 uma prepara\u00e7\u00e3o anterior e um projeto evolutivo que abrange todo o per\u00edodo de nossa exist\u00eancia em um novo corpo, onde est\u00e3o previstos os resgates de nossos carmas. O ser humano precisa entender que o corpo \u00e9 apenas um instrumento do esp\u00edrito. Quem existe, na realidade, \u00e9 o esp\u00edrito. O corpo \u00e9 apenas uma m\u00e1quina que o esp\u00edrito usa, durante o tempo em que lhe for \u00fatil e depois abandona-o, como fazemos com o lixo de nossa casa, descartamos no monturo. Por isso, a import\u00e2ncia de estar consciente dessa realidade, porque nos afastar\u00e1 de atos que nos induzem ao carma, e assim a imagem no espelho da vida come\u00e7ar\u00e1 a tornar-se mais clara e mais iluminada, come\u00e7ando a demonstrar o nosso verdadeiro ser, ess\u00eancias Divinas, postas na mat\u00e9ria para experienciar o conhecimento e assim evoluir por sua pr\u00f3pria vontade e escolha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>16\/01\/2021 Aquilo que nos acontece na vida \u00e9 apenas o espelho de nossos pensamentos, nossas palavras e nossas obras de vidas passadas. Esquecemos que somos uma part\u00edcula Divina envolta em um corpo de carne e disso resulta que somos tamb\u00e9m criadores de tudo o que nos diz a respeito. Temos o livre-arb\u00edtrio e disso tudo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16319"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16319"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16319\/revisions"}],"predecessor-version":[{"id":16320,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16319\/revisions\/16320"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}