{"id":16307,"date":"2023-06-12T09:09:15","date_gmt":"2023-06-12T12:09:15","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16307"},"modified":"2023-06-12T09:09:18","modified_gmt":"2023-06-12T12:09:18","slug":"plv3415-livro-24-diario-13-01-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3415-livro-24-diario-13-01-2021\/","title":{"rendered":"PLV3415 &#8211; Livro 24 &#8211; Di\u00e1rio, 13\/01\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>13\/01\/2021<\/strong><\/p>\n\n\n\n<p>O princ\u00edpio que estabelece todas as coisas \u00e9 Deus em a\u00e7\u00e3o. Deus \u00e9 uma energia, Deus \u00e9 luz, pur\u00edssima luz. Os seres s\u00f3 podem ver as luzes ou reflexos das coisas materiais. N\u00e3o podem, com os olhos da carne, ver a luz que emana de Deus. Poucos videntes t\u00eam essa acuidade visual, que n\u00e3o \u00e9 do corpo f\u00edsico, mas dos olhos da alma. Essa energia, que \u00e9 Deus, \u00e9 o sustent\u00e1culo de todos os seres, quer sejam f\u00edsicos, do \u00e1tomo \u00e0s gal\u00e1xias, quer sejam os n\u00e3o f\u00edsicos, que existem, mas nossos olhos n\u00e3o conseguem ver. Tenha-se como exemplo as Col\u00f4nias Espirituais, que h\u00e1 em grande quantidade acima da Terra. Essas Col\u00f4nias, em grande parte, s\u00e3o o reduto para onde v\u00e3o os esp\u00edritos rec\u00e9m-desencarnados, para l\u00e1 se readaptarem novamente ao conv\u00edvio espiritual. Quando Jo\u00e3o nos diz no Evangelho, 10:34, ele n\u00e3o estava alegando compara\u00e7\u00e3o alguma que se encrustou no conhecimento e express\u00e3o da humanidade atual, para expressar o suprassumo de uma atividade, mas no que diz cada palavra de sua senten\u00e7a: \u201c<em>V\u00f3s Sois Deuses<\/em>\u201d. Essa \u00e9 a realidade, tudo no universo \u00e9 Deus, na diferencia\u00e7\u00e3o da frequ\u00eancia e intensidade de sua energia. Por exemplo, a Terra est\u00e1 mudando a sua energia, porque \u00e9 isso que a levar\u00e1 \u00e0 quinta dimens\u00e3o. Se sua energia n\u00e3o se alterar, continuar\u00e1 na terceira dimens\u00e3o. Por que um \u00e1tomo n\u00e3o agrega outro el\u00e9tron? \u00c9 s\u00f3 porque diferem as suas energias. N\u00e3o existe um Deus sentado em um trono, porque Ele \u00e9 tudo o que existe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\/01\/2021 O princ\u00edpio que estabelece todas as coisas \u00e9 Deus em a\u00e7\u00e3o. Deus \u00e9 uma energia, Deus \u00e9 luz, pur\u00edssima luz. Os seres s\u00f3 podem ver as luzes ou reflexos das coisas materiais. N\u00e3o podem, com os olhos da carne, ver a luz que emana de Deus. Poucos videntes t\u00eam essa acuidade visual, que n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16307"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16307"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16307\/revisions"}],"predecessor-version":[{"id":16308,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16307\/revisions\/16308"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}