{"id":16294,"date":"2023-06-09T14:25:46","date_gmt":"2023-06-09T17:25:46","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=16294"},"modified":"2023-06-09T14:25:49","modified_gmt":"2023-06-09T17:25:49","slug":"plv3412-livro-24-diario-10-01-2021","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/plv3412-livro-24-diario-10-01-2021\/","title":{"rendered":"PLV3412 &#8211; Livro 24 &#8211; Di\u00e1rio, 10\/01\/2021"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>10\/01\/2021<\/strong><\/p>\n\n\n\n<p>No nosso caminhar evolutivo, reencontramos os passos que foram dados em vidas passadas. Ainda n\u00e3o nos acostumamos com aquela lei que determina propriamente a estrada que estamos trilhando e a que iremos trilhar. Diz a lei: \u201c<em>A todo o ato, h\u00e1 um outro ato na mesma intensidade, mas em sentido contr\u00e1rio<\/em>\u201d. Essa lei, propriamente, d\u00e1 sentido \u00e0 nossa l\u00f3gica e raz\u00e3o, porque nos mostra que sempre recebemos de volta aquilo de n\u00f3s saiu. Uma vez que isso se instala em nosso consciente exterior, come\u00e7a a influenciar o consciente do corpo a antever o resultado de seus pr\u00f3prios atos. J\u00e1 o torna consciente de que todos os atos insanos, ter\u00e3o que ser, hoje ou amanh\u00e3, resgatados. O resgate geralmente \u00e9 mais do\u00eddo do que o ato em si. Por um simples motivo: o ato pode ter sido apenas um impulso, mas, para corrigir esse impulso insano, talvez seja necess\u00e1ria at\u00e9 uma vida inteira no corpo. N\u00e3o sabemos quando ser\u00e1 o resgate, isso \u00e9 aquilatado pelo Conselho C\u00e1rmico, que determina no projeto da pr\u00f3xima exist\u00eancia f\u00edsica o que vai resgatar ou o que fica para as pr\u00f3ximas. Ao esp\u00edrito, cabe apenas resgatar aquilo que lhe \u00e9 poss\u00edvel nesta sua encarna\u00e7\u00e3o e que est\u00e1 estabelecido em seu projeto de reencarna\u00e7\u00e3o. Conforme o peso dos resgates, ser\u00e1 a dificuldade ou a facilidade de limpar-se nessa encarna\u00e7\u00e3o. N\u00e3o importa o tempo que leve, mas as portas do c\u00e9u somente se abrem quando o esp\u00edrito estiver t\u00e3o alvo como quando saiu do Criador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10\/01\/2021 No nosso caminhar evolutivo, reencontramos os passos que foram dados em vidas passadas. Ainda n\u00e3o nos acostumamos com aquela lei que determina propriamente a estrada que estamos trilhando e a que iremos trilhar. Diz a lei: \u201cA todo o ato, h\u00e1 um outro ato na mesma intensidade, mas em sentido contr\u00e1rio\u201d. Essa lei, propriamente, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16294"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=16294"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16294\/revisions"}],"predecessor-version":[{"id":16295,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/16294\/revisions\/16295"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=16294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=16294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=16294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}