{"id":12328,"date":"2020-11-08T07:23:07","date_gmt":"2020-11-08T10:23:07","guid":{"rendered":"https:\/\/www.miguelfaccio.com.br\/blog\/?p=12328"},"modified":"2020-11-08T07:23:10","modified_gmt":"2020-11-08T10:23:10","slug":"rcd2350-raios-ou-chamas-2","status":"publish","type":"post","link":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/rcd2350-raios-ou-chamas-2\/","title":{"rendered":"RCD2350\u2013 Raios ou Chamas"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>MENSAGENS DE JAV\u00e9<\/strong><\/p>\n\n\n\n<p>continua\u00e7\u00e3o<\/p>\n\n\n\n<p>As primeiras almas que encarnaram aqui na Terra eram de origem Terrena.<\/p>\n\n\n\n<p>Pertenciam ao astral da Terra.<\/p>\n\n\n\n<p>Almas simples, sem maldade.<\/p>\n\n\n\n<p>Praticavam at\u00e9 o canibalismo na ideia de possuir a coragem alheia.<\/p>\n\n\n\n<p>Olhei para frente novamente e vi algo de muito bom para todos eles.<\/p>\n\n\n\n<p>As pr\u00e1ticas de jogos entre tribos j\u00e1 iam por bom caminho.<\/p>\n\n\n\n<p>Quando recebi um presente indesejado.<\/p>\n\n\n\n<p>Meu amigo Jesus me procurou em car\u00e1ter preocupado.<\/p>\n\n\n\n<p>Recebi a not\u00edcia com compreens\u00e3o e responsabilidade que tenho diante de Deus.<\/p>\n\n\n\n<p>Os homens se dividiam em planeta distante.<\/p>\n\n\n\n<p>O Ego que acompanha voc\u00eas todos por quase toda eternidade me pregava mais uma pe\u00e7a.<\/p>\n\n\n\n<p>\u201cMas Jesus porque se dividiram assim t\u00e3o r\u00e1pido\u201d?<\/p>\n\n\n\n<p>\u201cIntoler\u00e2ncia&#8230;Intoler\u00e2ncia, Jav\u00e9\u201d<\/p>\n\n\n\n<p>Medi o tamanho do problema com olho milim\u00e9trico, mas tudo in\u00fatil.<\/p>\n\n\n\n<p>Porque jamais recusaria um pedido de meu amigo Jesus.<\/p>\n\n\n\n<p>Em quest\u00e3o de dias as naves pousavam no planeta Terra trazendo milh\u00f5es de almas j\u00e1 deca\u00eddas para o astral da Terra.<\/p>\n\n\n\n<p>O homem terreno sentia pela primeira vez a sensa\u00e7\u00e3o do mal.<\/p>\n\n\n\n<p>Em pouco tempo estas almas j\u00e1 se organizavam no astral da Terra em permuta de sensa\u00e7\u00f5es di\u00e1ria com os humanos encarnados.<\/p>\n\n\n\n<p>Assim iniciava eu, Jav\u00e9 um trabalho de prote\u00e7\u00e3o aos humanos nativos do planeta e uma guerra com os l\u00edderes da revolu\u00e7\u00e3o no astral.<\/p>\n\n\n\n<p>Foram tempos dif\u00edceis, tempos que n\u00e3o gosto sequer de lembrar.<\/p>\n\n\n\n<p>A roupa humana feita de carne pura n\u00e3o foi aceita pelos revoltosos.<\/p>\n\n\n\n<p>Caso aceitassem logo o esquecimento como rem\u00e9dio tudo seria diferente.<\/p>\n\n\n\n<p>Mas queriam guardar a intelig\u00eancia agu\u00e7ada de Orion.<\/p>\n\n\n\n<p>De nada adiantaria encarnar estes seres com as lembran\u00e7as dos ideais revolucion\u00e1rios.<\/p>\n\n\n\n<p>Seria como mudar de casa, nada mais.<\/p>\n\n\n\n<p>Pacientemente negociei vantagens as quais sempre cumpri para que aceitassem nascer em corpos carnais com esquecimento.<\/p>\n\n\n\n<p>Nasciam ricos, belos e ocupavam papel de destaque nas sociedades.<\/p>\n\n\n\n<p>Como nos dias de hoje ainda cumpro com tais tratados.<\/p>\n\n\n\n<p>Sou homem de palavra e tenho que assim ser.<\/p>\n\n\n\n<p>Ent\u00e3o at\u00e9 hoje nascem ricos, belos e inteligentes e conseguem muitas coisas ao longo da vida terrena.<\/p>\n\n\n\n<p>Continuam com suas maldades ainda por mais alguns dias.<\/p>\n\n\n\n<p>Tudo est\u00e1 no fim Marcio.<\/p>\n\n\n\n<p>Est\u00e1 chegando o dia de entregar nas m\u00e3os de Jesus o \u00faltimo cidad\u00e3o recuperado.<\/p>\n\n\n\n<p>Poder\u00e3o voltar as estrelas de Orion recuperados.<\/p>\n\n\n\n<p>A\u00ed ficarei com todos que n\u00e3o conseguiram se recuperar a fim de separar o Joio e o Trigo junto com Jesus.<\/p>\n\n\n\n<p>Reerguerei as m\u00e3os a Deus por mais um trabalho cumprido e pedirei a Deus que aben\u00e7oe a nova empreitada que estarei assumindo em planeta distante daqui.<\/p>\n\n\n\n<p>Onde prometo recuperar estes retardat\u00e1rios com mais trabalho.<\/p>\n\n\n\n<p>Nenhuma ovelha se perdera, eu, Jav\u00e9 assim prometo.&nbsp;<\/p>\n\n\n\n<p>Jesus meu amigo acompanhar\u00e1 voc\u00eas que ficar\u00e3o na Terra para o final dos tempos e inicio de novos tempos para sempre e eternamente rumo a Deus.<\/p>\n\n\n\n<p>Fiquem com Deus.<\/p>\n\n\n\n<p>Jav\u00e9.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MENSAGENS DE JAV\u00e9 continua\u00e7\u00e3o As primeiras almas que encarnaram aqui na Terra eram de origem Terrena. Pertenciam ao astral da Terra. Almas simples, sem maldade. Praticavam at\u00e9 o canibalismo na ideia de possuir a coragem alheia. Olhei para frente novamente e vi algo de muito bom para todos eles. As pr\u00e1ticas de jogos entre tribos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/12328"}],"collection":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=12328"}],"version-history":[{"count":1,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/12328\/revisions"}],"predecessor-version":[{"id":12329,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/posts\/12328\/revisions\/12329"}],"wp:attachment":[{"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=12328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=12328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.miguelfaccio.com.br\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=12328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}